{"id":266,"date":"2022-07-07T01:26:41","date_gmt":"2022-07-07T01:26:41","guid":{"rendered":"https:\/\/www.technofox-international.com\/?post_type=produits&#038;p=266"},"modified":"2022-07-07T01:50:42","modified_gmt":"2022-07-07T01:50:42","slug":"eco-shine","status":"publish","type":"produits","link":"https:\/\/www.technofox-international.com\/de_at\/produits\/eco-shine\/","title":{"rendered":"Eco-Shine"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"266\" class=\"elementor elementor-266\" data-elementor-post-type=\"produits\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3948fc9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3948fc9e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4570fdd8\" data-id=\"4570fdd8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64621db4 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64621db4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.technofox-international.com\/de_at\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Technofox<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b2e62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b2e62\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f2a8281\" data-id=\"6f2a8281\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-396b254a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"396b254a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2c591aad\" data-id=\"2c591aad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66c257b4 elementor-widget elementor-widget-image\" data-id=\"66c257b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1421\" height=\"1706\" src=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray.png\" class=\"attachment-full size-full wp-image-274\" alt=\"\" srcset=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray.png 1421w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray-250x300.png 250w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray-853x1024.png 853w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray-768x922.png 768w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-shine-bidon-et-spray-1279x1536.png 1279w\" sizes=\"(max-width: 1421px) 100vw, 1421px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c3e1a10\" data-id=\"5c3e1a10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c9f75a0 elementor-widget elementor-widget-text-editor\" data-id=\"6c9f75a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Technofox Eco-Shine ist ein Reiniger und ein Schutzwachs f\u00fcr die Reinigung ohne Wasser.\u00a0<\/p><ul><li>Reiniger und Schutzwachs f\u00fcr die wasserlose Reinigung<\/li><li>kann auf jeder Oberfl\u00e4che verwendet werden; Karosserie, Glas, Plastik und Leder<\/li><li>Ideal f\u00fcr die Nachbearbeitung von Fahrzeugen nach einer Politur oder bei der Reinigung<\/li><li>sch\u00fctzt das Material und hinterl\u00e4sst einen dezenten, angenehmen Geruch<\/li><li>wird mit einem Mikrofasertuch oder als Schmiermittel bei der Dekontaminierung verwendet<\/li><li>einfach zu verwenden und frei von sch\u00e4dlichen Stoffen<\/li><li>leicht gl\u00e4nzende Schlussnote<\/li><li>ohne Silikon<\/li><\/ul><p>Produkt ist in 1L-Spraydosen und 20L-Kanistern erh\u00e4ltlich.<\/p><p><strong>Frei von VOCs und Stoffen, die f\u00fcr den Benutzer und die Umwelt sch\u00e4dlich sind.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59f432 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59f432\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f8dd536\" data-id=\"7f8dd536\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-502936ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"502936ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48153023 elementor-widget elementor-widget-heading\" data-id=\"48153023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WIRD VON HUNDERTEN VON MALSTUDIOS AUF DER GANZEN WELT VERWENDET,  <br>UNSERE L\u00d6SUNG ERM\u00d6GLICHT EINE ERHEBLICHE REDUZIERUNG DER COV-EMISSIONEN SOWIE<br> ALS DIE ENTSTEHUNG VON GIFTM\u00dcLL.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b945170 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b945170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31eaa76b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31eaa76b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12ba0b57\" data-id=\"12ba0b57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b294e9b elementor-flip-box--direction-right elementor-flip-box--effect-flip elementor-widget elementor-widget-flip-box\" data-id=\"6b294e9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tReinigt effektiv l\u00f6sungsmittelhaltige Farben\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tEco-Shine ist ein sehr vielseitiges Produkt, das sowohl f\u00fcr die \u00e4u\u00dfere Karosserie des Fahrzeugs als auch f\u00fcr die Reinigung des Innenraums (Plastik, Leder, Bildschirm ...) verwendet werden kann.\n\nEs kann auch zum Reinigen von Fenstern verwendet werden, wenn Sie ein sauberes, saugf\u00e4higes Mikrofasertuch verwenden.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-17d9fbb7\" data-id=\"17d9fbb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dea9870 elementor-flip-box--direction-right elementor-flip-box--effect-flip elementor-widget elementor-widget-flip-box\" data-id=\"5dea9870\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tEinfach und effektiv\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tSpr\u00fchen Sie das Produkt auf die zu reinigende Oberfl\u00e4che und wischen\/polieren Sie es einfach mit einem sauberen, saugf\u00e4higen Mikrofasertuch ab, um eine saubere, makellose Oberfl\u00e4che zu erhalten.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-64abd408\" data-id=\"64abd408\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f136c9a elementor-flip-box--direction-right elementor-flip-box--effect-flip elementor-widget elementor-widget-flip-box\" data-id=\"1f136c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tOhne Risiko f\u00fcr Ihre Gesundheit\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\tUnsere Produkte enthalten keine sch\u00e4dlichen und gef\u00e4hrlichen Stoffe. Dadurch wird das Gesundheitsrisiko f\u00fcr die Mitarbeiter und das Auftreten von brennbaren und explosiven Gasen in Lackierwerkst\u00e4tten erheblich reduziert.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c4a938d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c4a938d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f27e702\" data-id=\"4f27e702\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12fca58b elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"12fca58b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tAndere Produkte der Reihe Technofox\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a186ae0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a186ae0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53023386\" data-id=\"53023386\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ed4508 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"63ed4508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1267\" height=\"1620\" src=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face.png\" class=\"attachment-full size-full wp-image-95\" alt=\"\" srcset=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face.png 1267w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face-235x300.png 235w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face-801x1024.png 801w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face-768x982.png 768w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/05\/eco-clean-plus-face-1201x1536.png 1201w\" sizes=\"(max-width: 1267px) 100vw, 1267px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ECO CLEAN PLUS<\/h3><p class=\"elementor-image-box-description\">Die Produktreihe Eco-Clean von Technofox erm\u00f6glicht die Durchf\u00fchrung s\u00e4mtlicher Reinigungs- und Waschvorg\u00e4nge wie die auf dem Markt befindlichen Verd\u00fcnner.\nEs wird effizient in einer automatischen Waschmaschine verwendet: TF-ONE<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7d75a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e7d75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.technofox-international.com\/de_at\/produits\/eco-clean-plus\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56f80073\" data-id=\"56f80073\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5070d4d7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5070d4d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"885\" height=\"1072\" src=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-wash-bidon-34-e1563199551168-2.png\" class=\"attachment-full size-full wp-image-268\" alt=\"\" srcset=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-wash-bidon-34-e1563199551168-2.png 885w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-wash-bidon-34-e1563199551168-2-248x300.png 248w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-wash-bidon-34-e1563199551168-2-845x1024.png 845w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/eco-wash-bidon-34-e1563199551168-2-768x930.png 768w\" sizes=\"(max-width: 885px) 100vw, 885px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ECO-WASH<\/h3><p class=\"elementor-image-box-description\">Eco-Wash ist eine sehr starke L\u00f6sung zum Entfetten von neuen Teilen oder nach dem Schleifen. Es bietet eine saubere Oberfl\u00e4che vor dem Lackieren.\nErsetzt l\u00f6sungsmittelhaltige und alkoholische Entfetter mit einem einzigen wirksamen Produkt.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8ddf4c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5a8ddf4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.technofox-international.com\/de_at\/produits\/eco-wash\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6e774b03\" data-id=\"6e774b03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51c4ab62 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"51c4ab62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"975\" src=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/wipe-and-wash-e1560353469798.png\" class=\"attachment-full size-full wp-image-243\" alt=\"\" srcset=\"https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/wipe-and-wash-e1560353469798.png 1200w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/wipe-and-wash-e1560353469798-300x244.png 300w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/wipe-and-wash-e1560353469798-1024x832.png 1024w, https:\/\/www.technofox-international.com\/wp-content\/uploads\/2022\/07\/wipe-and-wash-e1560353469798-768x624.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">WIPE&amp;WASH<\/h3><p class=\"elementor-image-box-description\">\nBesonders strapazierf\u00e4hige Vliesstoff-Entfettungst\u00fccher f\u00fcr alle Reinigungsarbeiten in der Lackiererei in Kombination mit ECO-WASH und ECO-SHINE. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d423b3b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7d423b3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.technofox-international.com\/de_at\/produits\/wipewash\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ea09bef elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ea09bef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65f4e43a\" data-id=\"65f4e43a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c2030c4 elementor-widget elementor-widget-spacer\" data-id=\"2c2030c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c79e780\" data-id=\"1c79e780\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a247c99 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2a247c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FORDERN SIE EINE DEMONSTRATION AN<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443e6bcf elementor-widget elementor-widget-text-editor\" data-id=\"443e6bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Produkte k\u00f6nnen das Risiko von schweren Krankheiten und Arbeitsunf\u00e4llen verringern und unseren Planeten sch\u00fctzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-173edf62 fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"173edf62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_3 ffs_default_wrap'><form data-form_id=\"3\" id=\"fluentform_3\" class=\"frm-fluent-form fluent_form_3 ff-el-form-top ff_form_instance_3_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_3_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Ein Demo anfordern<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='266' \/><input type=\"hidden\" id=\"_fluentform_3_fluentformnonce\" name=\"_fluentform_3_fluentformnonce\" value=\"3635272288\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de_at\/wp-json\/wp\/v2\/produits\/266\" \/><div data-type=\"name-element\" data-name=\"names\" class=\"ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_first_name_' id='label_ff_3_names_first_name_' >Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_3_names_first_name_\" class=\"ff-el-form-control\" aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_last_name_' id='label_ff_3_names_last_name_' >Vorname<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_3_names_last_name_\" class=\"ff-el-form-control\" aria-invalid=\"false\" aria-required=\"false\"><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_email' id='label_ff_3_email' aria-label=\"E-Mail\">E-Mail<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_3_email\" class=\"ff-el-form-control\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_dropdown' id='label_ff_3_dropdown' aria-label=\"W\u00e4hlen Sie Ihr Produkt aus\">W\u00e4hlen Sie Ihr Produkt aus<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_3_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_3_dropdown\"><option value=\"\">- W\u00e4hlen -<\/option><option value=\"ECO-CLEAN PLUS\"  >ECO-CLEAN PLUS<\/option><option value=\"ECO CLEAN\"  >ECO CLEAN<\/option><option value=\"TECHNOGRAFF\"  >TECHNOGRAFF<\/option><option value=\"AQUA-CLEAN\"  >AQUA-CLEAN<\/option><option value=\"ECO-CLEAN INDUSTRY\"  >ECO-CLEAN INDUSTRY<\/option><option value=\"TF-ONE\"  >TF-ONE<\/option><option value=\"TF-TWO\"  >TF-TWO<\/option><option value=\"TF-DOUBLE\"  >TF-DOUBLE<\/option><option value=\"TF-FOUR\"  >TF-FOUR<\/option><option value=\"TF-COMPACT\"  >TF-COMPACT<\/option><option value=\"ECO-WASH\"  >ECO-WASH<\/option><option value=\"ECO-SHINE\"  >ECO-SHINE<\/option><option value=\"ECO-WASH-PLUS\"  >ECO-WASH-PLUS<\/option><option value=\"PAINT REMOVER\"  >PAINT REMOVER<\/option><option value=\"HAND CLEANER\"  >HAND CLEANER<\/option><option value=\"WIPE &amp; WASH\"  >WIPE &amp; WASH<\/option><option value=\"MICROFIBRES\"  >MIKROFASER<\/option><option value=\"STOP-RUST\"  >STOP-RUST<\/option><option value=\"ABRASIVE 15\"  >ABRASIVE 15<\/option><\/select><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Senden Sie\">Senden Sie<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"de_at\"\/><\/form><div id='fluentform_3_errors' class='ff-errors-in-stack ff_form_instance_3_1 ff-form-loading_errors ff_form_instance_3_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_3_1 = {\"id\":\"3\",\"ajaxUrl\":\"https:\\\/\\\/www.technofox-international.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"id\":\"39\",\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_3_1\",\"form_id_selector\":\"fluentform_3\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\"}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"Ce champ est obligatoire\"}}},\"debounce_time\":300,\"conditionals\":{\"names\":{\"type\":\"any\",\"status\":true,\"conditions\":[{\"field\":\"\",\"value\":\"\",\"operator\":\"\"}]}},\"file_upload_settings\":[]};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"","class_list":["post-266","produits","type-produits","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/produits\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/produits"}],"about":[{"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/types\/produits"}],"version-history":[{"count":7,"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/produits\/266\/revisions"}],"predecessor-version":[{"id":314,"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/produits\/266\/revisions\/314"}],"wp:attachment":[{"href":"https:\/\/www.technofox-international.com\/de_at\/wp-json\/wp\/v2\/media?parent=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}